{"id":937,"date":"2021-01-29T18:00:00","date_gmt":"2021-01-29T17:00:00","guid":{"rendered":"https:\/\/feuerwehr-wiesendangen.ch\/lokal\/?p=937"},"modified":"2021-02-28T20:52:43","modified_gmt":"2021-02-28T19:52:43","slug":"29-01-2021-waschbox-betonieren","status":"publish","type":"post","link":"https:\/\/feuerwehr-wiesendangen.ch\/lokal\/29-01-2021-waschbox-betonieren\/","title":{"rendered":"29.01.2021 &#8211; Waschbox betonieren"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Die vorbereiteten Schalungen der Waschbox-W\u00e4nde werden mit Beton gef\u00fcllt<\/p>\n\n\n\nngg_shortcode_0_placeholder\n","protected":false},"excerpt":{"rendered":"<p>Die vorbereiteten Schalungen der Waschbox-W\u00e4nde werden mit Beton gef\u00fcllt<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"wpmdr_menu":1,"wpmdr_menu_extended":{"individualPostRemove":1,"individualPostRemoveDate":1,"individualPostRemoveAuthor":1,"individualPostYoastRemovePublished":1,"individualPostYoastRemoveModified":1},"footnotes":""},"categories":[25],"tags":[],"class_list":["post-937","post","type-post","status-publish","format-standard","hentry","category-umbau-umbau"],"_links":{"self":[{"href":"https:\/\/feuerwehr-wiesendangen.ch\/lokal\/wp-json\/wp\/v2\/posts\/937","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/feuerwehr-wiesendangen.ch\/lokal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/feuerwehr-wiesendangen.ch\/lokal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/feuerwehr-wiesendangen.ch\/lokal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/feuerwehr-wiesendangen.ch\/lokal\/wp-json\/wp\/v2\/comments?post=937"}],"version-history":[{"count":1,"href":"https:\/\/feuerwehr-wiesendangen.ch\/lokal\/wp-json\/wp\/v2\/posts\/937\/revisions"}],"predecessor-version":[{"id":938,"href":"https:\/\/feuerwehr-wiesendangen.ch\/lokal\/wp-json\/wp\/v2\/posts\/937\/revisions\/938"}],"wp:attachment":[{"href":"https:\/\/feuerwehr-wiesendangen.ch\/lokal\/wp-json\/wp\/v2\/media?parent=937"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/feuerwehr-wiesendangen.ch\/lokal\/wp-json\/wp\/v2\/categories?post=937"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/feuerwehr-wiesendangen.ch\/lokal\/wp-json\/wp\/v2\/tags?post=937"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}