{"id":1447,"date":"2021-07-26T18:00:00","date_gmt":"2021-07-26T16:00:00","guid":{"rendered":"https:\/\/feuerwehr-wiesendangen.ch\/lokal\/?p=1447"},"modified":"2021-09-09T22:14:08","modified_gmt":"2021-09-09T20:14:08","slug":"26-07-2021-boeden","status":"publish","type":"post","link":"https:\/\/feuerwehr-wiesendangen.ch\/lokal\/26-07-2021-boeden\/","title":{"rendered":"26.07.2021 &#8211; B\u00f6den"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Ein weiterer gut sichtbarer Fortschritt sind die neu gegossenen B\u00f6den.<br>Auch im Aussenbereich erstrahlt der Schlauchturm wieder in neuem Glanz. Gut sichtbar sind auch die Oberlichter vom neuen Bereich<\/p>\n\n\n\nngg_shortcode_0_placeholder\n","protected":false},"excerpt":{"rendered":"<p>Ein weiterer gut sichtbarer Fortschritt sind die neu gegossenen B\u00f6den.Auch im Aussenbereich erstrahlt der Schlauchturm wieder in neuem Glanz. Gut sichtbar sind auch die Oberlichter vom neuen Bereich<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"wpmdr_menu":1,"wpmdr_menu_extended":{"individualPostRemove":1,"individualPostRemoveDate":1,"individualPostRemoveAuthor":1,"individualPostYoastRemovePublished":1,"individualPostYoastRemoveModified":1},"footnotes":""},"categories":[25],"tags":[],"class_list":["post-1447","post","type-post","status-publish","format-standard","hentry","category-umbau-umbau"],"_links":{"self":[{"href":"https:\/\/feuerwehr-wiesendangen.ch\/lokal\/wp-json\/wp\/v2\/posts\/1447","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/feuerwehr-wiesendangen.ch\/lokal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/feuerwehr-wiesendangen.ch\/lokal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/feuerwehr-wiesendangen.ch\/lokal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/feuerwehr-wiesendangen.ch\/lokal\/wp-json\/wp\/v2\/comments?post=1447"}],"version-history":[{"count":2,"href":"https:\/\/feuerwehr-wiesendangen.ch\/lokal\/wp-json\/wp\/v2\/posts\/1447\/revisions"}],"predecessor-version":[{"id":1449,"href":"https:\/\/feuerwehr-wiesendangen.ch\/lokal\/wp-json\/wp\/v2\/posts\/1447\/revisions\/1449"}],"wp:attachment":[{"href":"https:\/\/feuerwehr-wiesendangen.ch\/lokal\/wp-json\/wp\/v2\/media?parent=1447"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/feuerwehr-wiesendangen.ch\/lokal\/wp-json\/wp\/v2\/categories?post=1447"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/feuerwehr-wiesendangen.ch\/lokal\/wp-json\/wp\/v2\/tags?post=1447"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}